{"id":2901,"date":"2022-06-22T10:00:22","date_gmt":"2022-06-22T09:00:22","guid":{"rendered":"http:\/\/www.sectionclinique-rennes.fr\/nuevo\/?page_id=2901"},"modified":"2026-07-16T08:02:20","modified_gmt":"2026-07-16T07:02:20","slug":"mentions-legales-test","status":"publish","type":"page","link":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/contact\/mentions-legales-test\/","title":{"rendered":"Mentions l\u00e9gales"},"content":{"rendered":"<p><strong>D\u00e9finitions<\/strong><\/p>\n<p style=\"font-weight: 400;\">Client : tout professionnel ou personne physique capable au sens des articles 1123 et suivants du Code civil, ou personne morale, qui visite le Site objet des pr\u00e9sentes conditions g\u00e9n\u00e9rales.<br \/>\nPrestations et Services : <a href=\"http:\/\/www.sectionclinique-rennes.fr\">http:\/\/www.sectionclinique-rennes.fr\/<\/a>\u00a0met \u00e0 disposition des Clients :<\/p>\n<p style=\"font-weight: 400;\">Contenu : Ensemble des \u00e9l\u00e9ments constituants l\u2019information pr\u00e9sente sur le Site, notamment textes \u2013 images \u2013 vid\u00e9os.<\/p>\n<p style=\"font-weight: 400;\">Informations clients : Ci-apr\u00e8s d\u00e9nomm\u00e9 \u00ab Information (s) \u00bb qui correspondent \u00e0 l\u2019ensemble des donn\u00e9es personnelles susceptibles d\u2019\u00eatre d\u00e9tenues par http:\/\/www.sectionclinique-rennes.fr\/\u00a0pour la gestion de votre compte, de la gestion de la relation client et \u00e0 des fins d\u2019analyses et de statistiques.<\/p>\n<p style=\"font-weight: 400;\">Utilisateur : Internaute se connectant, utilisant le site susnomm\u00e9.<\/p>\n<p style=\"font-weight: 400;\">Informations personnelles : \u00ab Les informations qui permettent, sous quelque forme que ce soit, directement ou non, l\u2019identification des personnes physiques auxquelles elles s\u2019appliquent \u00bb (article 4 de la loi n\u00b0 78-17 du 6 janvier 1978).<\/p>\n<p style=\"font-weight: 400;\">Les termes \u00ab donn\u00e9es \u00e0 caract\u00e8re personnel \u00bb, \u00ab personne concern\u00e9e \u00bb, \u00ab sous traitant \u00bb et \u00ab donn\u00e9es sensibles \u00bb ont le sens d\u00e9fini par le R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD : n\u00b0 2016-679)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>1. Pr\u00e9sentation du site<\/strong><\/p>\n<p>En vertu de l&rsquo;article 6 de la loi n\u00b0 2004-575 du 21 juin 2004 pour la confiance dans l&rsquo;\u00e9conomie num\u00e9rique, il est pr\u00e9cis\u00e9 aux utilisateurs du site http:\/\/www.sectionclinique-rennes.fr\/ l&rsquo;identit\u00e9 des diff\u00e9rents intervenants dans le cadre de sa r\u00e9alisation et de son suivi :<\/p>\n<p><strong>Propri\u00e9taire<\/strong> : Association UFORCA-Rennes \u2013 2, rue Victor Hugo &#8211; 35000 Rennes<br \/>\n<strong>Cr\u00e9ateur<\/strong> : <a href=\"http:\/\/www.sectionclinique-rennes.fr\/\">Emmanuelle Bernard &amp; Charles Cullard<\/a><br \/>\n<strong>Responsable publication<\/strong> : Jean Luc Monnier \u2013 monnierj@orange.fr<br \/>\nLe responsable publication est une personne physique ou une personne morale.<br \/>\n<strong>Webmaster<\/strong> : Thomas Kusmierzyk \u00a0\u2013 thomaskusmierzyk@gmail.fr<br \/>\n<strong>Cr\u00e9ation du logo :<\/strong> Charles Cullard,<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-content\/uploads\/2015\/08\/logo.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1386\" src=\"http:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-content\/uploads\/2015\/08\/logo-300x69.png\" alt=\"logo\" width=\"300\" height=\"69\" srcset=\"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-content\/uploads\/2015\/08\/logo-300x69.png 300w, https:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-content\/uploads\/2015\/08\/logo-1024x236.png 1024w, https:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-content\/uploads\/2015\/08\/logo-250x58.png 250w, https:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-content\/uploads\/2015\/08\/logo-150x35.png 150w, https:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-content\/uploads\/2015\/08\/logo.png 1199w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><br \/>\n<strong>H\u00e9bergeur<\/strong> : OVH \u2013 2 rue Kellermann &#8211; 59100 Roubaix<\/p>\n<p style=\"font-weight: 400;\"><strong>D\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es<\/strong> : Responsable des donn\u00e9es personnelles de l\u2019Association UFORCA-Rennes \u2013 sectionclinique35@gmail.com<\/p>\n<p><strong>Cr\u00e9dits<\/strong> : les mentions l\u00e9gales ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es et offertes par Subdelirium <a href=\"http:\/\/www.subdelirium.com\/competences\/creation-de-sites-web\/creation-de-site-internet-en-charente\/creation-de-site-internet-angouleme\/\" target=\"_blank\" rel=\"noopener\">cr\u00e9ation de site internet Angoul\u00eame<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>2. Conditions g\u00e9n\u00e9rales d\u2019utilisation du site et des services propos\u00e9s<\/strong><\/p>\n<p style=\"font-weight: 400;\">Le Site constitue une oeuvre de l\u2019esprit prot\u00e9g\u00e9e par les dispositions du Code de la Propri\u00e9t\u00e9 Intellectuelle et des R\u00e9glementations Internationales applicables.<\/p>\n<p style=\"font-weight: 400;\">Le Client ne peut en aucune mani\u00e8re r\u00e9utiliser, c\u00e9der ou exploiter pour son propre compte tout ou partie des \u00e9l\u00e9ments ou travaux du Site.<\/p>\n<p>L\u2019utilisation du site <a href=\"http:\/\/www.sectionclinique-rennes.fr\">http:\/\/www.sectionclinique-rennes.fr\/<\/a> implique l\u2019acceptation pleine et enti\u00e8re des conditions g\u00e9n\u00e9rales d\u2019utilisation ci-apr\u00e8s d\u00e9crites. Ces conditions d\u2019utilisation sont susceptibles d\u2019\u00eatre modifi\u00e9es ou compl\u00e9t\u00e9es \u00e0 tout moment, les utilisateurs du site http:\/\/www.sectionclinique-rennes.fr\/ sont donc invit\u00e9s \u00e0 les consulter de mani\u00e8re r\u00e9guli\u00e8re.<\/p>\n<p>Ce site est normalement accessible \u00e0 tout moment aux utilisateurs. Une interruption pour raison de maintenance technique peut \u00eatre toutefois d\u00e9cid\u00e9e par Association UFORCA-Rennes, qui s\u2019efforcera alors de communiquer pr\u00e9alablement aux utilisateurs les dates et heures de l\u2019intervention.<\/p>\n<p>Le site <a href=\"http:\/\/www.sectionclinique-rennes.fr\">http:\/\/www.sectionclinique-rennes.fr\/<\/a> est mis \u00e0 jour r\u00e9guli\u00e8rement par Thomas Kusmierzyk. De la m\u00eame fa\u00e7on, les mentions l\u00e9gales peuvent \u00eatre modifi\u00e9es \u00e0 tout moment : elles s\u2019imposent n\u00e9anmoins \u00e0 l\u2019utilisateur qui est invit\u00e9 \u00e0 s\u2019y r\u00e9f\u00e9rer le plus souvent possible afin d\u2019en prendre connaissance.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>3. Description des services fournis<\/strong><\/p>\n<p>Le site <a href=\"http:\/\/www.sectionclinique-rennes.fr\">http:\/\/www.sectionclinique-rennes.fr\/<\/a> a pour objet de fournir une information concernant l\u2019ensemble des activit\u00e9s de son association.<\/p>\n<p>Association UFORCA-Rennes s\u2019efforce de fournir sur le site <a href=\"http:\/\/www.sectionclinique-rennes.fr\">http:\/\/www.sectionclinique-rennes.fr\/<\/a> des informations aussi pr\u00e9cises que possible. Toutefois, il ne pourra \u00eatre tenue responsable des omissions, des inexactitudes et des carences dans la mise \u00e0 jour, qu\u2019elles soient de son fait ou du fait des tiers partenaires qui lui fournissent ces informations.<\/p>\n<p>Tous les informations indiqu\u00e9es sur le site<a href=\"http:\/\/www.sectionclinique-rennes.fr\"> http:\/\/www.sectionclinique-rennes.fr\/<\/a> sont donn\u00e9es \u00e0 titre indicatif, et sont susceptibles d\u2019\u00e9voluer. Par ailleurs, les renseignements figurant sur le site <a href=\"http:\/\/www.sectionclinique-rennes.fr\">http:\/\/www.sectionclinique-rennes.fr\/<\/a> ne sont pas exhaustifs. Ils sont donn\u00e9s sous r\u00e9serve de modifications ayant \u00e9t\u00e9 apport\u00e9es depuis leur mise en ligne.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>4. Limitations contractuelles sur les donn\u00e9es techniques<\/strong><\/p>\n<p>Le site utilise la technologie JavaScript.<\/p>\n<p>Le site Internet ne pourra \u00eatre tenu responsable de dommages mat\u00e9riels li\u00e9s \u00e0 l\u2019utilisation du site. De plus, l\u2019utilisateur du site s\u2019engage \u00e0 acc\u00e9der au site en utilisant un mat\u00e9riel r\u00e9cent, ne contenant pas de virus et avec un navigateur de derni\u00e8re g\u00e9n\u00e9ration mis-\u00e0-jour.<\/p>\n<p style=\"font-weight: 400;\">Le site\u00a0<a href=\"http:\/\/www.sectionclinique-rennes.fr\/\">http:\/\/www.sectionclinique-rennes.fr\/\u00a0<\/a>est h\u00e9berg\u00e9 chez un prestataire sur le territoire de l\u2019Union Europ\u00e9enne conform\u00e9ment aux dispositions du R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD : n\u00b0 2016-679)<\/p>\n<p style=\"font-weight: 400;\">L\u2019objectif est d\u2019apporter une prestation qui assure le meilleur taux d\u2019accessibilit\u00e9. L\u2019h\u00e9bergeur assure la continuit\u00e9 de son service 24 Heures sur 24, tous les jours de l\u2019ann\u00e9e. Il se r\u00e9serve n\u00e9anmoins la possibilit\u00e9 d\u2019interrompre le service d\u2019h\u00e9bergement pour les dur\u00e9es les plus courtes possibles notamment \u00e0 des fins de maintenance, d\u2019am\u00e9lioration de ses infrastructures, de d\u00e9faillance de ses infrastructures ou si les Prestations et Services g\u00e9n\u00e8rent un trafic r\u00e9put\u00e9 anormal.<\/p>\n<p style=\"font-weight: 400;\">Association UFORCA-Rennes et l\u2019h\u00e9bergeur ne pourront \u00eatre tenus responsables en cas de dysfonctionnement du r\u00e9seau Internet, des lignes t\u00e9l\u00e9phoniques ou du mat\u00e9riel informatique et de t\u00e9l\u00e9phonie li\u00e9 notamment \u00e0 l\u2019encombrement du r\u00e9seau emp\u00eachant l\u2019acc\u00e8s au serveur.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>5. Propri\u00e9t\u00e9 intellectuelle et contrefa\u00e7ons<\/strong><\/p>\n<p>Association UFORCA-Rennes est propri\u00e9taire des droits de propri\u00e9t\u00e9 intellectuelle ou d\u00e9tient les droits d\u2019usage sur tous les \u00e9l\u00e9ments accessibles sur le site, notamment les textes, images, graphismes, logo, ic\u00f4nes, sons, logiciels.<\/p>\n<p>Toute reproduction, repr\u00e9sentation, modification, publication, adaptation de tout ou partie des \u00e9l\u00e9ments du site\u00a0<a href=\"http:\/\/www.sectionclinique-rennes.fr\">http:\/\/www.sectionclinique-rennes.fr<\/a>\/, quel que soit le moyen ou le proc\u00e9d\u00e9 utilis\u00e9, est interdite, sauf autorisation \u00e9crite pr\u00e9alable de : Association UFORCA-Rennes.<\/p>\n<p>Toute exploitation non autoris\u00e9e du site ou de l\u2019un des \u00e9l\u00e9ments qu\u2019il contient sera consid\u00e9r\u00e9e comme constitutive d\u2019une contrefa\u00e7on et poursuivie conform\u00e9ment aux dispositions des articles L.335-2 et suivants du Code de Propri\u00e9t\u00e9 Intellectuelle.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>6. Limitations de responsabilit\u00e9<\/strong><\/p>\n<p style=\"font-weight: 400;\">Association UFORCA-Rennes agit en tant qu\u2019\u00e9diteur du site\u00a0<a href=\"https:\/\/grandesassisesamp2022.com\/\">http:\/\/www.sectionclinique-rennes.fr\/<\/a>\u00a0Association UFORCA-Rennes est responsable de la qualit\u00e9 et de la v\u00e9racit\u00e9 du Contenu qu\u2019il publie.<\/p>\n<p>Association UFORCA-Rennes ne pourra \u00eatre tenue responsable des dommages directs et indirects caus\u00e9s au mat\u00e9riel de l\u2019utilisateur, lors de l\u2019acc\u00e8s au site <a href=\"http:\/\/www.sectionclinique-rennes.fr\/\">http:\/\/www.sectionclinique-rennes.fr\/<\/a>, et r\u00e9sultant soit de l\u2019utilisation d\u2019un mat\u00e9riel ne r\u00e9pondant pas aux sp\u00e9cifications indiqu\u00e9es au point 4, soit de l\u2019apparition d\u2019un bug ou d\u2019une incompatibilit\u00e9.<\/p>\n<p>Association UFORCA-Rennes ne pourra \u00e9galement \u00eatre tenue responsable des dommages indirects (tels par exemple qu\u2019une perte de march\u00e9 ou perte d\u2019une chance) cons\u00e9cutifs \u00e0 l\u2019utilisation du site <a href=\"http:\/\/www.sectionclinique-rennes.fr\/\">http:\/\/www.sectionclinique-rennes.fr\/<\/a><\/p>\n<p>Des espaces interactifs (possibilit\u00e9 de poser des questions dans l\u2019espace contact) sont \u00e0 la disposition des utilisateurs. Association UFORCA-Rennes se r\u00e9serve le droit de supprimer, sans mise en demeure pr\u00e9alable, tout contenu d\u00e9pos\u00e9 dans cet espace qui contreviendrait \u00e0 la l\u00e9gislation applicable en France, en particulier aux dispositions relatives \u00e0 la protection des donn\u00e9es. Le cas \u00e9ch\u00e9ant, Association UFORCA-Rennes se r\u00e9serve \u00e9galement la possibilit\u00e9 de mettre en cause la responsabilit\u00e9 civile et\/ou p\u00e9nale de l\u2019utilisateur, notamment en cas de message \u00e0 caract\u00e8re raciste, injurieux, diffamant, ou pornographique, quel que soit le support utilis\u00e9 (texte, photographie\u2026).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>7. Gestion des donn\u00e9es personnelles<\/strong><\/p>\n<p style=\"font-weight: 400;\">Le Client est inform\u00e9 des r\u00e9glementations concernant la communication marketing, la loi du 21 Juin 2014 pour la confiance dans l\u2019Economie Num\u00e9rique, la Loi Informatique et Libert\u00e9 du 06 Ao\u00fbt 2004 ainsi que du R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD : n\u00b0 2016-679).<\/p>\n<p style=\"font-weight: 400;\"><strong>\u200b7.1 Responsables de la collecte des donn\u00e9es personnelles.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Pour les Donn\u00e9es Personnelles collect\u00e9es dans le cadre de la cr\u00e9ation du compte personnel de l\u2019Utilisateur et de sa navigation sur le Site, le responsable du traitement des Donn\u00e9es Personnelles est : Association UFORCA-Rennes. UFORCA-Rennes\u00a0est repr\u00e9sent\u00e9 par le bureau, son repr\u00e9sentant l\u00e9gal.<\/p>\n<p style=\"font-weight: 400;\">En tant que responsable du traitement des donn\u00e9es qu\u2019il collecte, Association UFORCA-Rennes s\u2019engage \u00e0 respecter le cadre des dispositions l\u00e9gales en vigueur. Il lui appartient notamment au Client d\u2019\u00e9tablir les finalit\u00e9s de ses traitements de donn\u00e9es, de fournir \u00e0 ses prospects et clients, \u00e0 partir de la collecte de leurs consentements, une information compl\u00e8te sur le traitement de leurs donn\u00e9es personnelles et de maintenir un registre des traitements conforme \u00e0 la r\u00e9alit\u00e9.<\/p>\n<p style=\"font-weight: 400;\">Chaque fois que Association UFORCA-Rennes\u00a0traite des Donn\u00e9es Personnelles, Association UFORCA-Rennes\u00a0prend toutes les mesures raisonnables pour s\u2019assurer de l\u2019exactitude et de la pertinence des Donn\u00e9es Personnelles au regard des finalit\u00e9s pour lesquelles\u00a0Association UFORCA-Rennes\u00a0les traite.<\/p>\n<p style=\"font-weight: 400;\">\u200b<\/p>\n<p style=\"font-weight: 400;\"><strong>7.2 Finalit\u00e9 des donn\u00e9es collect\u00e9es.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Association UFORCA-Rennes est susceptible de traiter tout ou partie des donn\u00e9es :<\/p>\n<p style=\"font-weight: 400;\">o \u00a0 pour permettre la navigation sur le Site et la gestion et la tra\u00e7abilit\u00e9 des prestations et services command\u00e9s par l\u2019utilisateur : donn\u00e9es de connexion et d\u2019utilisation du Site, facturation, historique des commandes, etc.<\/p>\n<p style=\"font-weight: 400;\">o \u00a0 pour pr\u00e9venir et lutter contre la fraude informatique (spamming, hacking\u2026) : mat\u00e9riel informatique utilis\u00e9 pour la navigation, l\u2019adresse IP, le mot de passe (hash\u00e9)<\/p>\n<p style=\"font-weight: 400;\">o \u00a0 pour am\u00e9liorer la navigation sur le Site : donn\u00e9es de connexion et d\u2019utilisation<\/p>\n<p style=\"font-weight: 400;\">o \u00a0 pour mener des enqu\u00eates de satisfaction facultatives sur\u00a0<a href=\"http:\/\/www.sectionclinique-rennes.fr\/\">http:\/\/www.sectionclinique-rennes.fr\/<\/a>\u00a0: adresse email<\/p>\n<p style=\"font-weight: 400;\">o \u00a0 pour mener des campagnes de communication (sms, mail) : num\u00e9ro de t\u00e9l\u00e9phone, adresse email<\/p>\n<p style=\"font-weight: 400;\">Association UFORCA-Rennes ne commercialise pas vos donn\u00e9es personnelles qui sont donc uniquement utilis\u00e9es par n\u00e9cessit\u00e9 ou \u00e0 des fins statistiques et d\u2019analyses.<\/p>\n<p style=\"font-weight: 400;\">\u200b<\/p>\n<p style=\"font-weight: 400;\"><strong>7.3 Droit d\u2019acc\u00e8s, de rectification et d\u2019opposition.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Conform\u00e9ment \u00e0 la r\u00e9glementation europ\u00e9enne en vigueur, les Utilisateurs de\u00a0<a href=\"http:\/\/www.sectionclinique-rennes.fr\/\">http:\/\/www.sectionclinique-rennes.fr\/<\/a>\u00a0disposent des droits suivants :<\/p>\n<p style=\"font-weight: 400;\">o \u00a0 droit d\u2019acc\u00e8s (article 15 RGPD) et de rectification (article 16 RGPD), de mise \u00e0 jour, de compl\u00e9tude des donn\u00e9es des Utilisateurs droit de verrouillage ou d\u2019effacement des donn\u00e9es des Utilisateurs \u00e0 caract\u00e8re personnel (article 17 du RGPD), lorsqu\u2019elles sont inexactes, incompl\u00e8tes, \u00e9quivoques, p\u00e9rim\u00e9es, ou dont la collecte, l\u2019utilisation, la communication ou la conservation est interdite<\/p>\n<p style=\"font-weight: 400;\">o \u00a0 droit de retirer \u00e0 tout moment un consentement (article 13-2c RGPD)<\/p>\n<p style=\"font-weight: 400;\">o \u00a0 droit \u00e0 la limitation du traitement des donn\u00e9es des Utilisateurs (article 18 RGPD)<\/p>\n<p style=\"font-weight: 400;\">o \u00a0 droit d\u2019opposition au traitement des donn\u00e9es des Utilisateurs (article 21 RGPD)<\/p>\n<p style=\"font-weight: 400;\">o \u00a0 droit \u00e0 la portabilit\u00e9 des donn\u00e9es que les Utilisateurs auront fournies, lorsque ces donn\u00e9es font l\u2019objet de traitements automatis\u00e9s fond\u00e9s sur leur consentement ou sur un contrat (article 20 RGPD)<\/p>\n<p style=\"font-weight: 400;\">o \u00a0 droit de d\u00e9finir le sort des donn\u00e9es des Utilisateurs apr\u00e8s leur mort et de choisir \u00e0 qui Association UFORCA-Rennes devra communiquer (ou non) ses donn\u00e9es \u00e0 un tiers qu\u2019il aura pr\u00e9alablement d\u00e9sign\u00e9<\/p>\n<p style=\"font-weight: 400;\">D\u00e8s que Association UFORCA-Rennes a connaissance du d\u00e9c\u00e8s d\u2019un Utilisateur et \u00e0 d\u00e9faut d\u2019instructions de sa part, Association UFORCA-Rennes s\u2019engage \u00e0 d\u00e9truire ses donn\u00e9es, sauf si leur conservation s\u2019av\u00e8re n\u00e9cessaire \u00e0 des fins probatoires ou pour r\u00e9pondre \u00e0 une obligation l\u00e9gale.<\/p>\n<p style=\"font-weight: 400;\">Si l\u2019Utilisateur souhaite savoir comment Association UFORCA-Rennes\u00a0utilise ses Donn\u00e9es Personnelles, demander \u00e0 les rectifier ou s\u2019oppose \u00e0 leur traitement, l\u2019Utilisateur peut contacter Association UFORCA-Rennes \u00a0par \u00e9crit \u00e0 l\u2019adresse suivante : sectionclinique35@gmail.com<\/p>\n<p style=\"font-weight: 400;\">Association UFORCA-Rennes \u2013 Responsable des donn\u00e9es personnelles de l&rsquo;Association UFORCA-Rennes<\/p>\n<p style=\"font-weight: 400;\">Dans ce cas, l\u2019Utilisateur doit indiquer les Donn\u00e9es Personnelles qu\u2019il souhaiterait que Association UFORCA-Rennes\u00a0corrige, mette \u00e0 jour ou supprime, en s\u2019identifiant pr\u00e9cis\u00e9ment avec une copie d\u2019une pi\u00e8ce d\u2019identit\u00e9 (carte d\u2019identit\u00e9 ou passeport).<\/p>\n<p style=\"font-weight: 400;\">Les demandes de suppression de Donn\u00e9es Personnelles seront soumises aux obligations qui sont impos\u00e9es \u00e0 Association UFORCA-Rennes par la loi, notamment en mati\u00e8re de conservation ou d\u2019archivage des documents. Enfin, les Utilisateurs de\u00a0<a href=\"http:\/\/www.sectionclinique-rennes.fr\/\">http:\/\/www.sectionclinique-rennes.fr\/<\/a>\u00a0peuvent d\u00e9poser une r\u00e9clamation aupr\u00e8s des autorit\u00e9s de contr\u00f4le, et notamment de la CNIL (<a href=\"https:\/\/www.cnil.fr\/fr\/plaintes).\">https:\/\/www.cnil.fr\/fr\/plaintes).<\/a><\/p>\n<p style=\"font-weight: 400;\">\u200b<\/p>\n<p style=\"font-weight: 400;\"><strong>7.4 Non-communication des donn\u00e9es personnelles.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Association UFORCA-Renne s\u2019interdit de traiter, h\u00e9berger ou transf\u00e9rer les Informations collect\u00e9es sur ses Clients vers un pays situ\u00e9 en dehors de l\u2019Union europ\u00e9enne ou reconnu comme \u00ab non ad\u00e9quat \u00bb par la Commission europ\u00e9enne sans en informer pr\u00e9alablement le client. Pour autant, Association UFORCA-Rennes\u00a0reste libre du choix de ses sous-traitants techniques et commerciaux \u00e0 la condition qu\u2019il pr\u00e9sentent les garanties suffisantes au regard des exigences du R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD : n\u00b0 2016-679).<\/p>\n<p style=\"font-weight: 400;\">Association UFORCA-Renness\u2019engage \u00e0 prendre toutes les pr\u00e9cautions n\u00e9cessaires afin de pr\u00e9server la s\u00e9curit\u00e9 des Informations et notamment qu\u2019elles ne soient pas communiqu\u00e9es \u00e0 des personnes non autoris\u00e9es. Cependant, si un incident impactant l\u2019int\u00e9grit\u00e9 ou la confidentialit\u00e9 des Informations du Client est port\u00e9e \u00e0 la connaissance de Association UFORCA-Rennes, celle-ci devra dans les meilleurs d\u00e9lais informer le Client et lui communiquer les mesures de corrections prises. Par ailleurs, Association UFORCA-Rennes\u00a0ne collecte aucune \u00ab donn\u00e9es sensibles \u00bb.<\/p>\n<p style=\"font-weight: 400;\">Les Donn\u00e9es Personnelles de l\u2019Utilisateur peuvent \u00eatre trait\u00e9es par des filiales de Association UFORCA-Rennes et des sous-traitants (prestataires de services), exclusivement afin de r\u00e9aliser les finalit\u00e9s de la pr\u00e9sente politique.<\/p>\n<p style=\"font-weight: 400;\">Dans la limite de leurs attributions respectives et pour les finalit\u00e9s rappel\u00e9es ci-dessus, les principales personnes susceptibles d\u2019avoir acc\u00e8s aux donn\u00e9es des Utilisateurs de\u00a0<a href=\"http:\/\/www.sectionclinique-rennes.fr\/\">http:\/\/www.sectionclinique-rennes.fr\/<\/a>\u00a0sont principalement les agents de notre service client.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>8 &#8211; Notification d\u2019incident.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Quels que soient les efforts fournis, aucune m\u00e9thode de transmission sur Internet et aucune m\u00e9thode de stockage \u00e9lectronique n\u2019est compl\u00e8tement s\u00fbre. Nous ne pouvons en cons\u00e9quence pas garantir une s\u00e9curit\u00e9 absolue.<\/p>\n<p style=\"font-weight: 400;\">Si nous prenions connaissance d\u2019une br\u00e8che de la s\u00e9curit\u00e9, nous avertirions les utilisateurs concern\u00e9s afin qu\u2019ils puissent prendre les mesures appropri\u00e9es. Nos proc\u00e9dures de notification d\u2019incident tiennent compte de nos obligations l\u00e9gales, qu\u2019elles se situent au niveau national ou europ\u00e9en. Nous nous engageons \u00e0 informer pleinement nos clients de toutes les questions relevant de la s\u00e9curit\u00e9 de leur compte et \u00e0 leur fournir toutes les informations n\u00e9cessaires pour les aider \u00e0 respecter leurs propres obligations r\u00e9glementaires en mati\u00e8re de reporting.<\/p>\n<p style=\"font-weight: 400;\">Aucune information personnelle de l\u2019utilisateur du site\u00a0<a href=\"http:\/\/www.sectionclinique-rennes.fr\/\">http:\/\/www.sectionclinique-rennes.fr\/<\/a>\u00a0n\u2019est publi\u00e9e \u00e0 l\u2019insu de l\u2019utilisateur, \u00e9chang\u00e9e, transf\u00e9r\u00e9e, c\u00e9d\u00e9e ou vendue sur un support quelconque \u00e0 des tiers. Seule l\u2019hypoth\u00e8se du rachat de\u00a0<a href=\"http:\/\/www.sectionclinique-rennes.fr\/\">http:\/\/www.sectionclinique-rennes.fr\/<\/a>\u00a0et de ses droits permettrait la transmission des dites informations \u00e0 l\u2019\u00e9ventuel acqu\u00e9reur qui serait \u00e0 son tour tenu de la m\u00eame obligation de conservation et de modification des donn\u00e9es vis \u00e0 vis de l\u2019utilisateur du site\u00a0<a href=\"http:\/\/www.sectionclinique-rennes.fr\/\">http:\/\/www.sectionclinique-rennes.fr\/<\/a>.<\/p>\n<p style=\"font-weight: 400;\">S\u00e9curit\u00e9.<\/p>\n<p style=\"font-weight: 400;\">Pour assurer la s\u00e9curit\u00e9 et la confidentialit\u00e9 des Donn\u00e9es Personnelles et des Donn\u00e9es Personnelles de Sant\u00e9,\u00a0<a href=\"http:\/\/www.sectionclinique-rennes.fr\/\">http:\/\/www.sectionclinique-rennes.fr\/<\/a>\u00a0utilise des r\u00e9seaux prot\u00e9g\u00e9s par des dispositifs standards tels que par pare-feu, la pseudonymisation, l\u2019encryption et mot de passe.<\/p>\n<p style=\"font-weight: 400;\">Lors du traitement des Donn\u00e9es Personnelles,\u00a0<a href=\"http:\/\/www.sectionclinique-rennes.fr\/\">http:\/\/www.sectionclinique-rennes.fr\/<\/a>\u00a0comprend toutes les mesures raisonnables visant \u00e0 les prot\u00e9ger contre toute perte, utilisation d\u00e9tourn\u00e9e, acc\u00e8s non autoris\u00e9, divulgation, alt\u00e9ration ou destruction.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>9. Liens hypertextes et cookies<\/strong><\/p>\n<p style=\"font-weight: 400;\">Le site\u00a0<a href=\"http:\/\/www.sectionclinique-rennes.fr\/\">http:\/\/www.sectionclinique-rennes.fr\/<\/a>\u00a0contient un certain nombre de liens hypertextes vers d\u2019autres sites, mis en place avec l\u2019autorisation de Association UFORCA-Rennes.<\/p>\n<p style=\"font-weight: 400;\">Cependant, Association UFORCA-Rennes n\u2019a pas la possibilit\u00e9 de v\u00e9rifier le contenu des sites ainsi visit\u00e9s, et n\u2019assumera en cons\u00e9quence aucune responsabilit\u00e9 de ce fait.<\/p>\n<p style=\"font-weight: 400;\">Sauf si vous d\u00e9cidez de d\u00e9sactiver les cookies, vous acceptez que le site puisse les utiliser. Vous pouvez \u00e0 tout moment d\u00e9sactiver ces cookies et ce gratuitement \u00e0 partir des possibilit\u00e9s de d\u00e9sactivation qui vous sont offertes et rappel\u00e9es ci-apr\u00e8s, sachant que cela peut r\u00e9duire ou emp\u00eacher l\u2019accessibilit\u00e9 \u00e0 tout ou partie des Services propos\u00e9s par le site.<\/p>\n<p style=\"font-weight: 400;\">\u200b<\/p>\n<p style=\"font-weight: 400;\"><strong>9.1. \u00ab COOKIES \u00bb.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Un \u00ab cookie \u00bb est un petit fichier d\u2019information envoy\u00e9 sur le navigateur de l\u2019Utilisateur et enregistr\u00e9 au sein du terminal de l\u2019Utilisateur (ex : ordinateur, smartphone), (ci-apr\u00e8s \u00ab Cookies \u00bb). Ce fichier comprend des informations telles que le nom de domaine de l\u2019Utilisateur, le fournisseur d\u2019acc\u00e8s Internet de l\u2019Utilisateur, le syst\u00e8me d\u2019exploitation de l\u2019Utilisateur, ainsi que la date et l\u2019heure d\u2019acc\u00e8s. Les Cookies ne risquent en aucun cas d\u2019endommager le terminal de l\u2019Utilisateur.<\/p>\n<p style=\"font-weight: 400;\">Association UFORCA-Rennes est susceptible de traiter les informations de l\u2019Utilisateur concernant sa visite du Site, telles que les pages consult\u00e9es, les recherches effectu\u00e9es. Ces informations permettent \u00e0\u00a0\u00a0Association UFORCA-Rennesd\u2019am\u00e9liorer le contenu du Site, de la navigation de l\u2019Utilisateur.<\/p>\n<p style=\"font-weight: 400;\">Les Cookies facilitant la navigation et\/ou la fourniture des services propos\u00e9s par le Site, l\u2019Utilisateur peut configurer son navigateur pour qu\u2019il lui permette de d\u00e9cider s\u2019il souhaite ou non les accepter de mani\u00e8re \u00e0 ce que des Cookies soient enregistr\u00e9s dans le terminal ou, au contraire, qu\u2019ils soient rejet\u00e9s, soit syst\u00e9matiquement, soit selon leur \u00e9metteur. L\u2019Utilisateur peut \u00e9galement configurer son logiciel de navigation de mani\u00e8re \u00e0 ce que l\u2019acceptation ou le refus des Cookies lui soient propos\u00e9s ponctuellement, avant qu\u2019un Cookie soit susceptible d\u2019\u00eatre enregistr\u00e9 dans son terminal. Association UFORCA-Rennes\u00a0informe l\u2019Utilisateur que, dans ce cas, il se peut que les fonctionnalit\u00e9s de son logiciel de navigation ne soient pas toutes disponibles.<\/p>\n<p style=\"font-weight: 400;\">Si l\u2019Utilisateur refuse l\u2019enregistrement de Cookies dans son terminal ou son navigateur, ou si l\u2019Utilisateur supprime ceux qui y sont enregistr\u00e9s, l\u2019Utilisateur est inform\u00e9 que sa navigation et son exp\u00e9rience sur le Site peuvent \u00eatre limit\u00e9es. Cela pourrait \u00e9galement \u00eatre le cas lorsque Association UFORCA-Rennes\u00a0\u00a0<a href=\"http:\/\/www.sectionclinique-rennes.fr\/\">http:\/\/www.sectionclinique-rennes.fr\/<\/a>\u00a0ou l\u2019un de ses prestataires ne peut pas reconna\u00eetre, \u00e0 des fins de compatibilit\u00e9 technique, le type de navigateur utilis\u00e9 par le terminal, les param\u00e8tres de langue et d\u2019affichage ou le pays depuis lequel le terminal semble connect\u00e9 \u00e0 Internet.<\/p>\n<p style=\"font-weight: 400;\">Le cas \u00e9ch\u00e9ant, Association UFORCA-Rennes\u00a0d\u00e9cline toute responsabilit\u00e9 pour les cons\u00e9quences li\u00e9es au fonctionnement d\u00e9grad\u00e9 du Site et des services \u00e9ventuellement propos\u00e9s par Association UFORCA-Rennes, r\u00e9sultant (i) du refus de Cookies par l\u2019Utilisateur (ii) de l\u2019impossibilit\u00e9 pour Association UFORCA-Rennes\u00a0d\u2019enregistrer ou de consulter les Cookies n\u00e9cessaires \u00e0 leur fonctionnement du fait du choix de l\u2019Utilisateur. Pour la gestion des Cookies et des choix de l\u2019Utilisateur, la configuration de chaque navigateur est diff\u00e9rente. Elle est d\u00e9crite dans le menu d\u2019aide du navigateur, qui permettra de savoir de quelle mani\u00e8re l\u2019Utilisateur peut modifier ses souhaits en mati\u00e8re de Cookies.<\/p>\n<p style=\"font-weight: 400;\">\u00c0 tout moment, l\u2019Utilisateur peut faire le choix d\u2019exprimer et de modifier ses souhaits en mati\u00e8re de Cookies.Association UFORCA-Rennes\u00a0pourra en outre faire appel aux services de prestataires externes pour l\u2019aider \u00e0 recueillir et traiter les informations d\u00e9crites dans cette section.<\/p>\n<p style=\"font-weight: 400;\">Enfin, en cliquant sur les ic\u00f4nes d\u00e9di\u00e9es aux r\u00e9seaux sociaux Twitter, Facebook, figurant sur le Site de \u00a0<a href=\"http:\/\/www.sectionclinique-rennes.fr\/\">http:\/\/www.sectionclinique-rennes.fr\/<\/a>\u00a0ou dans son application mobile et si l\u2019Utilisateur a accept\u00e9 le d\u00e9p\u00f4t de cookies en poursuivant sa navigation sur le Site Internet ou l\u2019application mobile de\u00a0<a href=\"http:\/\/www.sectionclinique-rennes.fr\/\">http:\/\/www.sectionclinique-rennes.fr\/<\/a>, Twitter, Facebook, peuvent \u00e9galement d\u00e9poser des cookies sur vos terminaux (ordinateur, tablette, t\u00e9l\u00e9phone portable).<\/p>\n<p style=\"font-weight: 400;\">Ces types de cookies ne sont d\u00e9pos\u00e9s sur vos terminaux qu\u2019\u00e0 condition que vous y consentiez, en continuant votre navigation sur le Site Internet ou l\u2019application mobile de\u00a0<a href=\"http:\/\/www.sectionclinique-rennes.fr\/\">http:\/\/www.sectionclinique-rennes.fr\/<\/a>. \u00c0 tout moment, l\u2019Utilisateur peut n\u00e9anmoins revenir sur son consentement \u00e0 ce que Association UFORCA-Rennes\u00a0d\u00e9pose ce type de cookies.<\/p>\n<p style=\"font-weight: 400;\">\u200b<\/p>\n<p style=\"font-weight: 400;\"><strong>Article 9.2. BALISES (\u201cTAGS\u201d) INTERNET.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Association UFORCA-Rennes\u00a0peut employer occasionnellement des balises Internet (\u00e9galement appel\u00e9es \u00ab tags \u00bb, ou balises d\u2019action, GIF \u00e0 un pixel, GIF transparents, GIF invisibles et GIF un \u00e0 un) et les d\u00e9ployer par l\u2019interm\u00e9diaire d\u2019un partenaire sp\u00e9cialiste d\u2019analyses Web susceptible de se trouver (et donc de stocker les informations correspondantes, y compris l\u2019adresse IP de l\u2019Utilisateur) dans un pays \u00e9tranger.<\/p>\n<p style=\"font-weight: 400;\">Ces balises sont plac\u00e9es \u00e0 la fois dans les publicit\u00e9s en ligne permettant aux internautes d\u2019acc\u00e9der au Site, et sur les diff\u00e9rentes pages de celui-ci.<\/p>\n<p style=\"font-weight: 400;\">Cette technologie permet \u00e0\u00a0Association UFORCA-Rennes\u00a0d\u2019\u00e9valuer les r\u00e9ponses des visiteurs face au Site et l\u2019efficacit\u00e9 de ses actions (par exemple, le nombre de fois o\u00f9 une page est ouverte et les informations consult\u00e9es), ainsi que l\u2019utilisation de ce Site par l\u2019Utilisateur.<\/p>\n<p style=\"font-weight: 400;\">Le prestataire externe pourra \u00e9ventuellement recueillir des informations sur les visiteurs du Site et d\u2019autres sites Internet gr\u00e2ce \u00e0 ces balises, constituer des rapports sur l\u2019activit\u00e9 du Site \u00e0 l\u2019attention de\u00a0Association UFORCA-Rennes, et fournir d\u2019autres services relatifs \u00e0 l\u2019utilisation de celui-ci et d\u2019Internet.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>10. Droit applicable et attribution de juridiction<\/strong><\/p>\n<p>Tout litige en relation avec l\u2019utilisation du site <a href=\"http:\/\/www.sectionclinique-rennes.fr\/\">http:\/\/www.sectionclinique-rennes.fr\/<\/a> est soumis au droit fran\u00e7ais. Il est fait attribution exclusive de juridiction aux tribunaux comp\u00e9tents de Rennes.<\/p>\n<p>&nbsp;<\/p>\n<h6><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9finitions Client : tout professionnel ou personne physique capable au sens des articles 1123 et suivants du Code civil, ou personne morale, qui visite le Site objet des pr\u00e9sentes conditions g\u00e9n\u00e9rales. Prestations et Services : http:\/\/www.sectionclinique-rennes.fr\/\u00a0met \u00e0 disposition des Clients : Contenu : Ensemble des \u00e9l\u00e9ments constituants l\u2019information pr\u00e9sente sur\u2026<\/p>\n<p> <a class=\"continue-reading-link\" href=\"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/contact\/mentions-legales-test\/\"><span>Continue reading<\/span><i class=\"crycon-right-dir\"><\/i><\/a> <\/p>\n","protected":false},"author":5,"featured_media":0,"parent":394,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-2901","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mentions l\u00e9gales - La Section clinique de Rennes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/contact\/mentions-legales-test\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mentions l\u00e9gales - La Section clinique de Rennes\" \/>\n<meta property=\"og:description\" content=\"D\u00e9finitions Client : tout professionnel ou personne physique capable au sens des articles 1123 et suivants du Code civil, ou personne morale, qui visite le Site objet des pr\u00e9sentes conditions g\u00e9n\u00e9rales. Prestations et Services : http:\/\/www.sectionclinique-rennes.fr\/\u00a0met \u00e0 disposition des Clients : Contenu : Ensemble des \u00e9l\u00e9ments constituants l\u2019information pr\u00e9sente sur\u2026 Continue reading\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/contact\/mentions-legales-test\/\" \/>\n<meta property=\"og:site_name\" content=\"La Section clinique de Rennes\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-16T07:02:20+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-content\/uploads\/2015\/08\/logo-300x69.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/contact\\\/mentions-legales-test\\\/\",\"url\":\"https:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/contact\\\/mentions-legales-test\\\/\",\"name\":\"Mentions l\u00e9gales - La Section clinique de Rennes\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/contact\\\/mentions-legales-test\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/contact\\\/mentions-legales-test\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/logo-300x69.png\",\"datePublished\":\"2022-06-22T09:00:22+00:00\",\"dateModified\":\"2026-07-16T07:02:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/contact\\\/mentions-legales-test\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/contact\\\/mentions-legales-test\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/contact\\\/mentions-legales-test\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/logo.png\",\"width\":1199,\"height\":276},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/contact\\\/mentions-legales-test\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\",\"item\":\"https:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/contact\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mentions l\u00e9gales\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/#website\",\"url\":\"http:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/\",\"name\":\"La Section clinique de Rennes\",\"description\":\"Association UFORCA\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/#organization\",\"name\":\"Section clinique de Rennes - Association UFORCA\",\"url\":\"http:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/logo.png\",\"contentUrl\":\"http:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/logo.png\",\"width\":1199,\"height\":276,\"caption\":\"Section clinique de Rennes - Association UFORCA\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sectionclinique-rennes.fr\\\/nuevo\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mentions l\u00e9gales - La Section clinique de Rennes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/contact\/mentions-legales-test\/","og_locale":"fr_FR","og_type":"article","og_title":"Mentions l\u00e9gales - La Section clinique de Rennes","og_description":"D\u00e9finitions Client : tout professionnel ou personne physique capable au sens des articles 1123 et suivants du Code civil, ou personne morale, qui visite le Site objet des pr\u00e9sentes conditions g\u00e9n\u00e9rales. Prestations et Services : http:\/\/www.sectionclinique-rennes.fr\/\u00a0met \u00e0 disposition des Clients : Contenu : Ensemble des \u00e9l\u00e9ments constituants l\u2019information pr\u00e9sente sur\u2026 Continue reading","og_url":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/contact\/mentions-legales-test\/","og_site_name":"La Section clinique de Rennes","article_modified_time":"2026-07-16T07:02:20+00:00","og_image":[{"url":"http:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-content\/uploads\/2015\/08\/logo-300x69.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/contact\/mentions-legales-test\/","url":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/contact\/mentions-legales-test\/","name":"Mentions l\u00e9gales - La Section clinique de Rennes","isPartOf":{"@id":"http:\/\/www.sectionclinique-rennes.fr\/nuevo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/contact\/mentions-legales-test\/#primaryimage"},"image":{"@id":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/contact\/mentions-legales-test\/#primaryimage"},"thumbnailUrl":"http:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-content\/uploads\/2015\/08\/logo-300x69.png","datePublished":"2022-06-22T09:00:22+00:00","dateModified":"2026-07-16T07:02:20+00:00","breadcrumb":{"@id":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/contact\/mentions-legales-test\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sectionclinique-rennes.fr\/nuevo\/contact\/mentions-legales-test\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/contact\/mentions-legales-test\/#primaryimage","url":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-content\/uploads\/2015\/08\/logo.png","contentUrl":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-content\/uploads\/2015\/08\/logo.png","width":1199,"height":276},{"@type":"BreadcrumbList","@id":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/contact\/mentions-legales-test\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/www.sectionclinique-rennes.fr\/nuevo\/"},{"@type":"ListItem","position":2,"name":"Contact","item":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/contact\/"},{"@type":"ListItem","position":3,"name":"Mentions l\u00e9gales"}]},{"@type":"WebSite","@id":"http:\/\/www.sectionclinique-rennes.fr\/nuevo\/#website","url":"http:\/\/www.sectionclinique-rennes.fr\/nuevo\/","name":"La Section clinique de Rennes","description":"Association UFORCA","publisher":{"@id":"http:\/\/www.sectionclinique-rennes.fr\/nuevo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.sectionclinique-rennes.fr\/nuevo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"http:\/\/www.sectionclinique-rennes.fr\/nuevo\/#organization","name":"Section clinique de Rennes - Association UFORCA","url":"http:\/\/www.sectionclinique-rennes.fr\/nuevo\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/www.sectionclinique-rennes.fr\/nuevo\/#\/schema\/logo\/image\/","url":"http:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-content\/uploads\/2015\/08\/logo.png","contentUrl":"http:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-content\/uploads\/2015\/08\/logo.png","width":1199,"height":276,"caption":"Section clinique de Rennes - Association UFORCA"},"image":{"@id":"http:\/\/www.sectionclinique-rennes.fr\/nuevo\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-json\/wp\/v2\/pages\/2901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-json\/wp\/v2\/comments?post=2901"}],"version-history":[{"count":8,"href":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-json\/wp\/v2\/pages\/2901\/revisions"}],"predecessor-version":[{"id":3561,"href":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-json\/wp\/v2\/pages\/2901\/revisions\/3561"}],"up":[{"embeddable":true,"href":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-json\/wp\/v2\/pages\/394"}],"wp:attachment":[{"href":"https:\/\/www.sectionclinique-rennes.fr\/nuevo\/wp-json\/wp\/v2\/media?parent=2901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}